
{"id":94038,"date":"2017-03-30T17:34:58","date_gmt":"2017-03-30T21:34:58","guid":{"rendered":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001.jpg"},"modified":"2017-03-30T17:34:58","modified_gmt":"2017-03-30T21:34:58","slug":"maria-zakrzeewska-001","status":"inherit","type":"attachment","link":"https:\/\/models.com\/oftheminute\/gleam-glisten-glow\/maria-zakrzeewska-001\/","title":{"rendered":"Maria-Zakrzeewska-001"},"author":444,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001.jpg'  rel=\"mfp\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-image-bGlnaHRib3gtZ2FsbGVyeS0w\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"502\" height=\"640\" src=\"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001-1012x1290.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001-1012x1290.jpg 1012w, https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001-803x1024.jpg 803w, https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001.jpg 2000w\" sizes=\"(max-width: 502px) 100vw, 502px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":2550,"file":"2017\/03\/Maria-Zakrzeewska-001.jpg","sizes":{"thumbnail":{"file":"Maria-Zakrzeewska-001-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001-150x150.jpg"},"medium":{"file":"Maria-Zakrzeewska-001-1012x1290.jpg","width":1012,"height":1290,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001-1012x1290.jpg"},"large":{"file":"Maria-Zakrzeewska-001-803x1024.jpg","width":803,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001-803x1024.jpg"},"post-thumbnail":{"file":"Maria-Zakrzeewska-001-75x70.jpg","width":75,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001-75x70.jpg"},"full":{"file":"Maria-Zakrzeewska-001.jpg","width":2000,"height":2550,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"DAVID_FERRUA","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":94021,"source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/03\/Maria-Zakrzeewska-001.jpg","_links":{"self":[{"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/media\/94038"}],"collection":[{"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/users\/444"}],"replies":[{"embeddable":true,"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/comments?post=94038"}]}}