
{"id":109477,"date":"2018-07-19T15:54:11","date_gmt":"2018-07-19T19:54:11","guid":{"rendered":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637.jpg"},"modified":"2018-07-19T15:54:11","modified_gmt":"2018-07-19T19:54:11","slug":"leomi-models-com3637","status":"inherit","type":"attachment","link":"https:\/\/models.com\/oftheminute\/leomie-anderson-wants-to-start-a-social-revolution\/leomi-models-com3637\/","title":{"rendered":"leomi-models.com3637"},"author":444,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637.jpg'  rel=\"mfp\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-image-bGlnaHRib3gtZ2FsbGVyeS0w\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"427\" height=\"640\" src=\"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637-427x640.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637-427x640.jpg 427w, https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637-853x1280.jpg 853w, https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637.jpg 2000w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":3000,"file":"2017\/10\/leomi-models.com3637.jpg","sizes":{"thumbnail":{"file":"leomi-models.com3637-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637-150x150.jpg"},"medium":{"file":"leomi-models.com3637-427x640.jpg","width":427,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637-427x640.jpg"},"large":{"file":"leomi-models.com3637-853x1280.jpg","width":853,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637-853x1280.jpg"},"full":{"file":"leomi-models.com3637.jpg","width":2000,"height":3000,"mime_type":"image\/jpeg","source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":99316,"source_url":"https:\/\/i.mdel.net\/oftheminute\/images\/2017\/10\/leomi-models.com3637.jpg","_links":{"self":[{"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/media\/109477"}],"collection":[{"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/users\/444"}],"replies":[{"embeddable":true,"href":"https:\/\/models.com\/oftheminute\/wp-json\/wp\/v2\/comments?post=109477"}]}}